{"id":45,"count":2,"description":"","link":"https:\/\/jochenhunger.com\/en\/t\/mathematik\/","name":"mathematik","slug":"mathematik","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>mathematik Archive - Jochen Hunger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jochenhunger.com\/en\/t\/mathematik\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mathematik Archive - Jochen Hunger\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jochenhunger.com\/en\/t\/mathematik\/\" \/>\n<meta property=\"og:site_name\" content=\"Jochen Hunger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/jochenhunger.com\/t\/mathematik\/\",\"url\":\"https:\/\/jochenhunger.com\/t\/mathematik\/\",\"name\":\"mathematik Archive - Jochen Hunger\",\"isPartOf\":{\"@id\":\"http:\/\/jochenhunger.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/jochenhunger.com\/t\/mathematik\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jochenhunger.com\/t\/mathematik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\/\/jochenhunger.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mathematik\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/jochenhunger.com\/#website\",\"url\":\"http:\/\/jochenhunger.com\/\",\"name\":\"Jochen Hunger\",\"description\":\"Museum &amp; exhibition design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/jochenhunger.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mathematik Archive - Jochen Hunger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jochenhunger.com\/en\/t\/mathematik\/","og_locale":"en_GB","og_type":"article","og_title":"mathematik Archive - Jochen Hunger","og_url":"https:\/\/jochenhunger.com\/en\/t\/mathematik\/","og_site_name":"Jochen Hunger","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/jochenhunger.com\/t\/mathematik\/","url":"https:\/\/jochenhunger.com\/t\/mathematik\/","name":"mathematik Archive - Jochen Hunger","isPartOf":{"@id":"http:\/\/jochenhunger.com\/#website"},"breadcrumb":{"@id":"https:\/\/jochenhunger.com\/t\/mathematik\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/jochenhunger.com\/t\/mathematik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/jochenhunger.com\/"},{"@type":"ListItem","position":2,"name":"mathematik"}]},{"@type":"WebSite","@id":"http:\/\/jochenhunger.com\/#website","url":"http:\/\/jochenhunger.com\/","name":"Jochen Hunger","description":"Museum &amp; exhibition design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/jochenhunger.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/jochenhunger.com\/en\/wp-json\/wp\/v2\/tags\/45","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jochenhunger.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/jochenhunger.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/jochenhunger.com\/en\/wp-json\/wp\/v2\/posts?tags=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}